{"id":3379,"date":"2025-06-27T10:33:11","date_gmt":"2025-06-27T10:33:11","guid":{"rendered":"https:\/\/kasteeloostvalkenburg.com\/?post_type=vacancy&#038;p=3379"},"modified":"2025-11-10T07:57:57","modified_gmt":"2025-11-10T07:57:57","slug":"selbststandiger-koch","status":"publish","type":"vacancy","link":"https:\/\/staging.kasteeloostvalkenburg.com\/de\/overig\/werken-bij\/selbststandiger-koch\/","title":{"rendered":"Chef de Partie"},"content":{"rendered":"\n<div class=\"ghostkit-grid ghostkit-grid-gap-md ghostkit-grid-justify-content-center\"><div class=\"ghostkit-grid-inner\">\n<div class=\"ghostkit-col ghostkit-col-lg-12 ghostkit-col-8\"><div class=\"ghostkit-col-content is-layout-flow wp-block-ghostkit-grid-column-is-layout-flow\">\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"afwashulp\">Chef de Partie<\/h2>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">Atmen Sie Gastfreundschaft? Gibt es f\u00fcr Sie nichts Sch\u00f6neres, als G\u00e4ste mit von Ihnen kreierten Gerichten zu verw\u00f6hnen? Wir sind auf der Suche nach einem talentierten und engagierten Chef de Partie, der unser K\u00fcchenteam verst\u00e4rkt.  <\/p>\n\n\n\r\n<div class=\"eye-block onpagenav \">\r\n    <div class=\"onpage-container\">\r\n        <nav id=\"onpage-nav\" aria-label=\"Inhoudsopgave\">\r\n            <ul class=\"onpage-nav-list\">\r\n                                    <li class=\"onpage-nav-item\">\r\n                        <a class=\"onpage-nav-link\" href=\"#ueber-kasteel-oost-section\">\u00dcber Kasteel Oost<\/a>\r\n                    <\/li>\r\n                                    <li class=\"onpage-nav-item\">\r\n                        <a class=\"onpage-nav-link\" href=\"#ueber-den-job-section\">\u00dcber den Job<\/a>\r\n                    <\/li>\r\n                                    <li class=\"onpage-nav-item\">\r\n                        <a class=\"onpage-nav-link\" href=\"#anwenden-section\">Anwenden<\/a>\r\n                    <\/li>\r\n                            <\/ul>\r\n        <\/nav>\r\n\r\n        <div id=\"mobile-nav-container\" class=\"d-flex d-md-none\">\r\n            <button id=\"mobile-nav-toggle\">Navigatie <i class=\"fas fa-angle-down\"><\/i><\/button>\r\n            <ul id=\"mobile-nav-list\">\r\n                                    <li class=\"onpage-nav-item\">\r\n                        <a class=\"onpage-nav-link\" href=\"#ueber-kasteel-oost-section\">\u00dcber Kasteel Oost<\/a>\r\n                    <\/li>\r\n                                    <li class=\"onpage-nav-item\">\r\n                        <a class=\"onpage-nav-link\" href=\"#ueber-den-job-section\">\u00dcber den Job<\/a>\r\n                    <\/li>\r\n                                    <li class=\"onpage-nav-item\">\r\n                        <a class=\"onpage-nav-link\" href=\"#anwenden-section\">Anwenden<\/a>\r\n                    <\/li>\r\n                            <\/ul>\r\n        <\/div>\r\n\r\n            <\/div>\r\n<\/div>\r\n\r\n<script>\r\n    document.addEventListener('DOMContentLoaded', function() {\r\n        const fixedNav = document.getElementById('onpage-nav-fixed');\r\n        const scrollThreshold = window.innerHeight;\r\n        const footerOffset = 780;\r\n        const mobileNavToggle = document.getElementById(\"mobile-nav-toggle\");\r\n        const mobileNavContainer = document.getElementById(\"mobile-nav-container\");\r\n        const mobileNavLinks = document.querySelectorAll(\".onpage-nav-link\");\r\n\r\n        const mobileNavContainerTop = mobileNavContainer.getBoundingClientRect().top + window.scrollY;\r\n\r\n        if (mobileNavToggle) {\r\n            mobileNavToggle.addEventListener(\"click\", function () {\r\n                mobileNavContainer.classList.toggle(\"active\");\r\n            });\r\n        }\r\n\r\n        if (mobileNavLinks) {\r\n            mobileNavLinks.forEach(link => {\r\n                link.addEventListener(\"click\", function () {\r\n                    mobileNavContainer.classList.remove(\"active\");\r\n                });\r\n            });\r\n        }\r\n\r\n        window.addEventListener('scroll', function() {\r\n            const scrollY = window.scrollY;\r\n            const pageHeight = document.documentElement.scrollHeight;\r\n            const windowHeight = window.innerHeight;\r\n            const distanceFromBottom = pageHeight - scrollY - windowHeight;\r\n\r\n            if (scrollY > mobileNavContainerTop) {\r\n                mobileNavContainer.classList.add(\"scrolled\");\r\n            } else {\r\n                mobileNavContainer.classList.remove(\"scrolled\");\r\n            }\r\n\r\n            if (scrollY > scrollThreshold) {\r\n                fixedNav.classList.add('visible');\r\n                mobileNavContainer.classList.add('scrolled');\r\n            } else {\r\n                fixedNav.classList.remove('visible');\r\n                mobileNavContainer.classList.remove('scrolled');\r\n            }\r\n\r\n            if (distanceFromBottom < footerOffset) {\r\n                fixedNav.classList.remove('visible');\r\n            }\r\n        });\r\n    });\r\n<\/script>\r\n\r\n\r\n\r\n<\/div><\/div>\n<\/div><\/div>\n\r\n<div class=\"eye-block empty-space empty-space--large pt-md-5 pb-md-5 pt-4 pb-4\" ><\/div>\r\n<div id=\"ueber-kasteel-oost-section\" class=\"eye-block menu-section\" title=\"ueber-kasteel-oost\" data-section-name=\"\u00dcber Kasteel Oost\"><\/div>\r\n\r\n    <div class=\"eye-block contentblock fade-in-animation\">\r\n        <div class=\"contentblock__image-right__container\">\r\n            <div class=\"contentblock__image-right\">\r\n                <div class=\"row\">\r\n                    <div class=\"col-12 col-lg-7 p-lg-1 d-flex align-items-center\">\r\n                        <div class=\"contentblock__image-right__content\">\r\n                                                        <h2>Kasteel Oost<\/h2>\r\n                            <div class=\"contentblock__image-right__content-text\">\r\n                                <p>Kasteel Oost auf Valkenburg ist ein einzigartiger Ort, an dem Erfahrung, Gastfreundschaft und Qualit\u00e4t zusammenkommen. In diesem wundersch\u00f6nen Schloss arbeiten wir jeden Tag leidenschaftlich daran, unvergessliche Momente f\u00fcr unsere G\u00e4ste zu schaffen. Von unserem Fine-Dining-Restaurant Mon R\u00eave \u00fcber ein attraktives Hotel, eine Hochzeits- und Eventlocation und bald auch einen Sch\u00f6nheitssalon und Wellness: Hier dreht sich alles darum, ein umfassendes und besonderes Erlebnis zu schaffen.  <\/p>\n<p>Als Mitarbeiter von Kasteel Oost spielen Sie eine wichtige Rolle dabei, dieses Erlebnis Wirklichkeit werden zu lassen. Ob Sie im Gastgewerbe, in der Gastronomie, im Verkauf oder in der Sch\u00f6nheitsbranche arbeiten &#8211; zusammen mit dem Team sorgen Sie daf\u00fcr, dass jedes Detail stimmt und sich jeder Gast besonders f\u00fchlt. Wir suchen Menschen mit einer Liebe zur Gastfreundschaft, einem Auge f\u00fcr Qualit\u00e4t und einer zupackenden Mentalit\u00e4t. Gemeinsam werden wir die n\u00e4chste Stufe dieses besonderen Ortes aufbauen.   <\/p>\n                            <\/div>\r\n\r\n                            \r\n                        <\/div>\r\n                    <\/div>\r\n                    <div class=\"col-12 col-lg-5 p-lg-1\">\r\n                        <div class=\"contentblock__image-right__image\">\r\n                            <img decoding=\"async\" data-speed=\"1.5\" src=\"https:\/\/staging.kasteeloostvalkenburg.com\/wp-content\/uploads\/2025\/03\/KOO_Aad_Valkenburg.jpeg\" alt=\"\">\r\n                        <\/div>\r\n                    <\/div>\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n\r\n\r\n<div class=\"eye-block empty-space empty-space--large pt-md-5 pb-md-5 pt-4 pb-4\" ><\/div>\r\n<div id=\"ueber-den-job-section\" class=\"eye-block menu-section\" title=\"ueber-den-job\" data-section-name=\"\u00dcber den Job\"><\/div>\r\n\n<div class=\"ghostkit-grid ghostkit-grid-gap-md ghostkit-grid-justify-content-center\"><div class=\"ghostkit-grid-inner\">\n<div class=\"ghostkit-col ghostkit-col-lg-12 ghostkit-col-8\"><div class=\"ghostkit-col-content is-layout-flow wp-block-ghostkit-grid-column-is-layout-flow\">\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"afwashulp\">\u00dcber diese Position<\/h2>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">Bei Kasteel Oost zu arbeiten bedeutet: in einem inspirierenden Umfeld zu kochen, jeden Tag mit frischen Produkten zu arbeiten, Raum f\u00fcr Kreativit\u00e4t und Wertsch\u00e4tzung f\u00fcr Ihre Arbeit zu bekommen. Sie werden Teil eines Teams sein, das ehrgeizig ist, aber ohne jede Attit\u00fcde. Wir wollen einfach nur gutes Essen machen, f\u00fcr Menschen, die es wirklich genie\u00dfen.  <\/p>\n<\/div><\/div>\n<\/div><\/div>\n\r\n<div class=\"eye-block empty-space empty-space--small pt-md-3 pb-md-3 pt-2 pb-2\" ><\/div>\n<div class=\"ghostkit-grid ghostkit-grid-gap-md equal-height-column\"><div class=\"ghostkit-grid-inner\">\n<div class=\"ghostkit-col ghostkit-col-md-12 ghostkit-col-6 equal-height-columns\"><div class=\"ghostkit-col-content is-layout-flow wp-block-ghostkit-grid-column-is-layout-flow\">\r\n<div class=\"eye-block custom-card bg--lightbeige\">\r\n    <div class=\"custom-card__content\">\r\n        <div class=\"acf-innerblocks-container\">\n\n<h4 class=\"wp-block-heading\" id=\"profiel\">Profil<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Als Chef de Partie leiten Sie Ihre eigene Gruppe (warm, kalt oder Schneebesen - je nach Erfahrung), \u00fcberwachen die Qualit\u00e4t und sorgen f\u00fcr einen reibungslosen Ablauf. Sie arbeiten eng mit dem K\u00fcchenchef und dem Sous-Chef zusammen und helfen bei der Entwicklung neuer Gerichte und Men\u00fcs. Sie werden viel Raum f\u00fcr Ihre eigene Initiative haben.  <\/p>\n\n<\/div>\r\n    <\/div>\r\n    <\/div><\/div><\/div>\n\n\n\n<div class=\"ghostkit-col ghostkit-col-md-12 ghostkit-col-6\"><div class=\"ghostkit-col-content is-layout-flow wp-block-ghostkit-grid-column-is-layout-flow\">\r\n<div class=\"eye-block custom-card bg--lightbeige\">\r\n    <div class=\"custom-card__content\">\r\n        <div class=\"acf-innerblocks-container\">\n\n<h4 class=\"wp-block-heading\" id=\"profiel\">Wer sind Sie?<\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Mindestens 2 Jahre Erfahrung in einer professionellen K\u00fcche.<\/li>\n\n\n\n<li>Jemand, der seinen Sender unabh\u00e4ngig betreiben kann.<\/li>\n\n\n\n<li>Strukturiert, stressresistent und mag gute Teamarbeit.<\/li>\n\n\n\n<li>Kenntnisse \u00fcber HACCP und Hygiene.<\/li>\n\n\n\n<li>Leidenschaft f\u00fcr das Kochen und der Wunsch, sich in einem eng verbundenen Team weiterzuentwickeln.<\/li>\n<\/ul>\n\n<\/div>\r\n    <\/div>\r\n    <\/div><\/div><\/div>\n<\/div><\/div>\n\r\n<div class=\"eye-block empty-space empty-space--small pt-md-3 pb-md-3 pt-2 pb-2\" ><\/div>\n<div class=\"ghostkit-grid ghostkit-grid-gap-md\"><div class=\"ghostkit-grid-inner\">\n<div class=\"ghostkit-col ghostkit-col-md-12 ghostkit-col-6\"><div class=\"ghostkit-col-content is-layout-flow wp-block-ghostkit-grid-column-is-layout-flow\">\r\n<div class=\"eye-block custom-card bg--lightbeige\">\r\n    <div class=\"custom-card__content\">\r\n        <div class=\"acf-innerblocks-container\">\n\n<h4 class=\"wp-block-heading\" id=\"wat-bieden-wij\">Was bieten wir an?<\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Ein einzigartiger Arbeitsplatz in einem sch\u00f6nen Schloss mit moderner K\u00fcche.<\/li>\n\n\n\n<li>Markt\u00fcbliches Gehalt + Trinkgeld und flexible Arbeitszeiten.<\/li>\n\n\n\n<li>Ernsthafte Wachstumschancen innerhalb des Teams.<\/li>\n\n\n\n<li>Faire Zeiteinteilung und Raum f\u00fcr freie Tage.<\/li>\n\n\n\n<li>Gelegenheit f\u00fcr Schulungen\/Kurse.<\/li>\n\n\n\n<li>Ein gem\u00fctliches und professionelles Team, in dem Humor und harte Arbeit Hand in Hand gehen.<\/li>\n<\/ul>\n\n<\/div>\r\n    <\/div>\r\n    <\/div><\/div><\/div>\n\n\n\n<div class=\"ghostkit-col ghostkit-col-md-12 ghostkit-col-6 is-layout-flow wp-block-ghostkit-grid-column-is-layout-flow\"><div class=\"ghostkit-col-content\"><\/div><\/div>\n<\/div><\/div>\n\r\n<div class=\"eye-block empty-space empty-space--large pt-md-5 pb-md-5 pt-4 pb-4\" ><\/div>\r\n<div id=\"anwenden-section\" class=\"eye-block menu-section\" title=\"anwenden\" data-section-name=\"Anwenden\"><\/div>\r\n\n<div class=\"ghostkit-grid ghostkit-grid-gap-md ghostkit-grid-justify-content-center\"><div class=\"ghostkit-grid-inner\">\n<div class=\"ghostkit-col ghostkit-col-lg-12 ghostkit-col-8\"><div class=\"ghostkit-col-content is-layout-flow wp-block-ghostkit-grid-column-is-layout-flow\">\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"afwashulp\">Enthusiastisch?<\/h2>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">Senden Sie Ihren Lebenslauf (oder nur eine kurze Nachricht) an <a href=\"mailto:michel@koonings.com\">michel@koonings.com.<\/a> M\u00f6chten Sie lieber zuerst anrufen oder sich bewerben? Auch gut. Wir sind offen f\u00fcr Gespr\u00e4che und Talente.   <\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">Wer wei\u00df, vielleicht begr\u00fc\u00dfen wir Sie schon bald in Kasteel Oost.<\/p>\n<\/div><\/div>\n<\/div><\/div>\n","protected":false},"template":"","meta":{"_acf_changed":false,"ghostkit_customizer_options":"","ghostkit_custom_css":"","ghostkit_custom_js_head":"","ghostkit_custom_js_foot":"","ghostkit_typography":""},"sector":[5],"class_list":["post-3379","vacancy","type-vacancy","status-publish","hentry","sector-horeca"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Chef de Partie - Kasteel Oost<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Chef de Partie - Kasteel Oost\" \/>\n<meta property=\"og:url\" content=\"https:\/\/staging.kasteeloostvalkenburg.com\/de\/overig\/werken-bij\/selbststandiger-koch\/\" \/>\n<meta property=\"og:site_name\" content=\"Kasteel Oost\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Kooningstheweddingpalace\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-10T07:57:57+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"2\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/staging.kasteeloostvalkenburg.com\/de\/overig\/werken-bij\/selbststandiger-koch\/\",\"url\":\"https:\/\/staging.kasteeloostvalkenburg.com\/de\/overig\/werken-bij\/selbststandiger-koch\/\",\"name\":\"Chef de Partie - Kasteel Oost\",\"isPartOf\":{\"@id\":\"https:\/\/staging.kasteeloostvalkenburg.com\/de\/#website\"},\"datePublished\":\"2025-06-27T10:33:11+00:00\",\"dateModified\":\"2025-11-10T07:57:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/staging.kasteeloostvalkenburg.com\/de\/overig\/werken-bij\/selbststandiger-koch\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/staging.kasteeloostvalkenburg.com\/de\/overig\/werken-bij\/selbststandiger-koch\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/staging.kasteeloostvalkenburg.com\/de\/overig\/werken-bij\/selbststandiger-koch\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/staging.kasteeloostvalkenburg.com\/de\/startseite\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Chef de Partie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/staging.kasteeloostvalkenburg.com\/de\/#website\",\"url\":\"https:\/\/staging.kasteeloostvalkenburg.com\/de\/\",\"name\":\"Kasteel Oost\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/staging.kasteeloostvalkenburg.com\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/staging.kasteeloostvalkenburg.com\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/staging.kasteeloostvalkenburg.com\/de\/#organization\",\"name\":\"Kasteel Oost\",\"url\":\"https:\/\/staging.kasteeloostvalkenburg.com\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/staging.kasteeloostvalkenburg.com\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/staging.kasteeloostvalkenburg.com\/wp-content\/uploads\/2025\/04\/KasteelOost-logo-darkgray.png\",\"contentUrl\":\"https:\/\/staging.kasteeloostvalkenburg.com\/wp-content\/uploads\/2025\/04\/KasteelOost-logo-darkgray.png\",\"width\":413,\"height\":318,\"caption\":\"Kasteel Oost\"},\"image\":{\"@id\":\"https:\/\/staging.kasteeloostvalkenburg.com\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Kooningstheweddingpalace\",\"https:\/\/www.instagram.com\/kasteeloost\/\",\"https:\/\/www.tiktok.com\/@kooningstheweddingpalace\",\"https:\/\/nl.pinterest.com\/koonings\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Chef de Partie - Kasteel Oost","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"de_DE","og_type":"article","og_title":"Chef de Partie - Kasteel Oost","og_url":"https:\/\/staging.kasteeloostvalkenburg.com\/de\/overig\/werken-bij\/selbststandiger-koch\/","og_site_name":"Kasteel Oost","article_publisher":"https:\/\/www.facebook.com\/Kooningstheweddingpalace","article_modified_time":"2025-11-10T07:57:57+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"2\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/staging.kasteeloostvalkenburg.com\/de\/overig\/werken-bij\/selbststandiger-koch\/","url":"https:\/\/staging.kasteeloostvalkenburg.com\/de\/overig\/werken-bij\/selbststandiger-koch\/","name":"Chef de Partie - Kasteel Oost","isPartOf":{"@id":"https:\/\/staging.kasteeloostvalkenburg.com\/de\/#website"},"datePublished":"2025-06-27T10:33:11+00:00","dateModified":"2025-11-10T07:57:57+00:00","breadcrumb":{"@id":"https:\/\/staging.kasteeloostvalkenburg.com\/de\/overig\/werken-bij\/selbststandiger-koch\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/staging.kasteeloostvalkenburg.com\/de\/overig\/werken-bij\/selbststandiger-koch\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/staging.kasteeloostvalkenburg.com\/de\/overig\/werken-bij\/selbststandiger-koch\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/staging.kasteeloostvalkenburg.com\/de\/startseite\/"},{"@type":"ListItem","position":2,"name":"Chef de Partie"}]},{"@type":"WebSite","@id":"https:\/\/staging.kasteeloostvalkenburg.com\/de\/#website","url":"https:\/\/staging.kasteeloostvalkenburg.com\/de\/","name":"Kasteel Oost","description":"","publisher":{"@id":"https:\/\/staging.kasteeloostvalkenburg.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/staging.kasteeloostvalkenburg.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/staging.kasteeloostvalkenburg.com\/de\/#organization","name":"Kasteel Oost","url":"https:\/\/staging.kasteeloostvalkenburg.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/staging.kasteeloostvalkenburg.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/staging.kasteeloostvalkenburg.com\/wp-content\/uploads\/2025\/04\/KasteelOost-logo-darkgray.png","contentUrl":"https:\/\/staging.kasteeloostvalkenburg.com\/wp-content\/uploads\/2025\/04\/KasteelOost-logo-darkgray.png","width":413,"height":318,"caption":"Kasteel Oost"},"image":{"@id":"https:\/\/staging.kasteeloostvalkenburg.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Kooningstheweddingpalace","https:\/\/www.instagram.com\/kasteeloost\/","https:\/\/www.tiktok.com\/@kooningstheweddingpalace","https:\/\/nl.pinterest.com\/koonings\/"]}]}},"_links":{"self":[{"href":"https:\/\/staging.kasteeloostvalkenburg.com\/de\/wp-json\/wp\/v2\/vacancy\/3379","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.kasteeloostvalkenburg.com\/de\/wp-json\/wp\/v2\/vacancy"}],"about":[{"href":"https:\/\/staging.kasteeloostvalkenburg.com\/de\/wp-json\/wp\/v2\/types\/vacancy"}],"wp:attachment":[{"href":"https:\/\/staging.kasteeloostvalkenburg.com\/de\/wp-json\/wp\/v2\/media?parent=3379"}],"wp:term":[{"taxonomy":"sector","embeddable":true,"href":"https:\/\/staging.kasteeloostvalkenburg.com\/de\/wp-json\/wp\/v2\/sector?post=3379"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}