{"id":1636,"date":"2025-03-21T13:54:33","date_gmt":"2025-03-21T13:54:33","guid":{"rendered":"https:\/\/kasteeloostvalkenburg.com\/overig\/werken-bij\/hilfe-in-der-kueche\/"},"modified":"2025-11-10T07:58:11","modified_gmt":"2025-11-10T07:58:11","slug":"hilfe-in-der-kueche","status":"publish","type":"vacancy","link":"https:\/\/staging.kasteeloostvalkenburg.com\/de\/overig\/werken-bij\/hilfe-in-der-kueche\/","title":{"rendered":"Hilfe in der K\u00fcche"},"content":{"rendered":"\n<div class=\"ghostkit-grid ghostkit-grid-gap-md ghostkit-grid-justify-content-center\"><div class=\"ghostkit-grid-inner\">\n<div class=\"ghostkit-col ghostkit-col-lg-12 ghostkit-col-8\"><div class=\"ghostkit-col-content is-layout-flow wp-block-ghostkit-grid-column-is-layout-flow\">\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"afwashulp\">Hilfe in der K\u00fcche<\/h2>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">Sind Sie ein vielseitiger K\u00fcchenhelfer, der Teil eines starken Teams sein m\u00f6chte und gerne die \u00c4rmel hochkrempelt? Dann bewerben Sie sich als K\u00fcchenhilfe bei dem sch\u00f6nsten Arbeitsplatz, den es gibt. <\/p>\n\n\n\r\n<div class=\"eye-block onpagenav \">\r\n    <div class=\"onpage-container\">\r\n        <nav id=\"onpage-nav\" aria-label=\"Inhoudsopgave\">\r\n            <ul class=\"onpage-nav-list\">\r\n                                    <li class=\"onpage-nav-item\">\r\n                        <a class=\"onpage-nav-link\" href=\"#ueber-kasteel-oost-section\">\u00dcber Kasteel Oost<\/a>\r\n                    <\/li>\r\n                                    <li class=\"onpage-nav-item\">\r\n                        <a class=\"onpage-nav-link\" href=\"#ueber-den-job-section\">\u00dcber den Job<\/a>\r\n                    <\/li>\r\n                                    <li class=\"onpage-nav-item\">\r\n                        <a class=\"onpage-nav-link\" href=\"#anwenden-section\">Anwenden<\/a>\r\n                    <\/li>\r\n                            <\/ul>\r\n        <\/nav>\r\n\r\n        <div id=\"mobile-nav-container\" class=\"d-flex d-md-none\">\r\n            <button id=\"mobile-nav-toggle\">Navigatie <i class=\"fas fa-angle-down\"><\/i><\/button>\r\n            <ul id=\"mobile-nav-list\">\r\n                                    <li class=\"onpage-nav-item\">\r\n                        <a class=\"onpage-nav-link\" href=\"#ueber-kasteel-oost-section\">\u00dcber Kasteel Oost<\/a>\r\n                    <\/li>\r\n                                    <li class=\"onpage-nav-item\">\r\n                        <a class=\"onpage-nav-link\" href=\"#ueber-den-job-section\">\u00dcber den Job<\/a>\r\n                    <\/li>\r\n                                    <li class=\"onpage-nav-item\">\r\n                        <a class=\"onpage-nav-link\" href=\"#anwenden-section\">Anwenden<\/a>\r\n                    <\/li>\r\n                            <\/ul>\r\n        <\/div>\r\n\r\n            <\/div>\r\n<\/div>\r\n\r\n<script>\r\n    document.addEventListener('DOMContentLoaded', function() {\r\n        const fixedNav = document.getElementById('onpage-nav-fixed');\r\n        const scrollThreshold = window.innerHeight;\r\n        const footerOffset = 780;\r\n        const mobileNavToggle = document.getElementById(\"mobile-nav-toggle\");\r\n        const mobileNavContainer = document.getElementById(\"mobile-nav-container\");\r\n        const mobileNavLinks = document.querySelectorAll(\".onpage-nav-link\");\r\n\r\n        const mobileNavContainerTop = mobileNavContainer.getBoundingClientRect().top + window.scrollY;\r\n\r\n        if (mobileNavToggle) {\r\n            mobileNavToggle.addEventListener(\"click\", function () {\r\n                mobileNavContainer.classList.toggle(\"active\");\r\n            });\r\n        }\r\n\r\n        if (mobileNavLinks) {\r\n            mobileNavLinks.forEach(link => {\r\n                link.addEventListener(\"click\", function () {\r\n                    mobileNavContainer.classList.remove(\"active\");\r\n                });\r\n            });\r\n        }\r\n\r\n        window.addEventListener('scroll', function() {\r\n            const scrollY = window.scrollY;\r\n            const pageHeight = document.documentElement.scrollHeight;\r\n            const windowHeight = window.innerHeight;\r\n            const distanceFromBottom = pageHeight - scrollY - windowHeight;\r\n\r\n            if (scrollY > mobileNavContainerTop) {\r\n                mobileNavContainer.classList.add(\"scrolled\");\r\n            } else {\r\n                mobileNavContainer.classList.remove(\"scrolled\");\r\n            }\r\n\r\n            if (scrollY > scrollThreshold) {\r\n                fixedNav.classList.add('visible');\r\n                mobileNavContainer.classList.add('scrolled');\r\n            } else {\r\n                fixedNav.classList.remove('visible');\r\n                mobileNavContainer.classList.remove('scrolled');\r\n            }\r\n\r\n            if (distanceFromBottom < footerOffset) {\r\n                fixedNav.classList.remove('visible');\r\n            }\r\n        });\r\n    });\r\n<\/script>\r\n\r\n\r\n\r\n<\/div><\/div>\n<\/div><\/div>\n\r\n<div class=\"eye-block empty-space empty-space--large pt-md-5 pb-md-5 pt-4 pb-4\" ><\/div>\r\n<div id=\"ueber-kasteel-oost-section\" class=\"eye-block menu-section\" title=\"ueber-kasteel-oost\" data-section-name=\"\u00dcber Kasteel Oost\"><\/div>\r\n\r\n    <div class=\"eye-block contentblock fade-in-animation\">\r\n        <div class=\"contentblock__image-right__container\">\r\n            <div class=\"contentblock__image-right\">\r\n                <div class=\"row\">\r\n                    <div class=\"col-12 col-lg-7 p-lg-1 d-flex align-items-center\">\r\n                        <div class=\"contentblock__image-right__content\">\r\n                                                        <h2>Kasteel Oost<\/h2>\r\n                            <div class=\"contentblock__image-right__content-text\">\r\n                                <p>Kasteel Oost auf Valkenburg ist ein einzigartiger Ort, an dem Erfahrung, Gastfreundschaft und Qualit\u00e4t zusammenkommen. In diesem wundersch\u00f6nen Schloss arbeiten wir jeden Tag leidenschaftlich daran, unvergessliche Momente f\u00fcr unsere G\u00e4ste zu schaffen. Von unserem Fine-Dining-Restaurant Mon R\u00eave \u00fcber ein attraktives Hotel, eine Hochzeits- und Eventlocation und bald auch einen Sch\u00f6nheitssalon und Wellness: Hier dreht sich alles darum, ein umfassendes und besonderes Erlebnis zu schaffen.  <\/p>\n<p>Als Mitarbeiter von Kasteel Oost spielen Sie eine wichtige Rolle dabei, dieses Erlebnis wahr werden zu lassen. Ob Sie im Gastgewerbe, in der Gastronomie, im Verkauf oder in der Sch\u00f6nheitsbranche arbeiten &#8211; Sie und das Team sorgen daf\u00fcr, dass jedes Detail stimmt und sich jeder Gast besonders f\u00fchlt.  Wir suchen Menschen mit einer Liebe zur Gastfreundschaft, einem Auge f\u00fcr Qualit\u00e4t und einer zupackenden Mentalit\u00e4t. Gemeinsam werden wir die n\u00e4chste Stufe dieses besonderen Ortes aufbauen. <\/p>\n                            <\/div>\r\n\r\n                            \r\n                        <\/div>\r\n                    <\/div>\r\n                    <div class=\"col-12 col-lg-5 p-lg-1\">\r\n                        <div class=\"contentblock__image-right__image\">\r\n                            <img decoding=\"async\" data-speed=\"1.5\" src=\"https:\/\/staging.kasteeloostvalkenburg.com\/wp-content\/uploads\/2025\/03\/KOO_Aad_Valkenburg.jpeg\" alt=\"\">\r\n                        <\/div>\r\n                    <\/div>\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n\r\n\r\n<div class=\"eye-block empty-space empty-space--large pt-md-5 pb-md-5 pt-4 pb-4\" ><\/div>\r\n<div id=\"ueber-den-job-section\" class=\"eye-block menu-section\" title=\"ueber-den-job\" data-section-name=\"\u00dcber den Job\"><\/div>\r\n\n<div class=\"ghostkit-grid ghostkit-grid-gap-md ghostkit-grid-justify-content-center\"><div class=\"ghostkit-grid-inner\">\n<div class=\"ghostkit-col ghostkit-col-lg-12 ghostkit-col-8\"><div class=\"ghostkit-col-content is-layout-flow wp-block-ghostkit-grid-column-is-layout-flow\">\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"afwashulp\">\u00dcber diese Position<\/h2>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">Als K\u00fcchenhilfe sind Sie ein echter Teil des Gastfreundschaftsteams von Koonings in Kasteel Oost in Valkenburg. Sie k\u00fcmmern sich um die K\u00fcche und sorgen daf\u00fcr, dass sie aufger\u00e4umt ist. Sie sp\u00fclen den Abwasch und helfen den K\u00f6chen hier und da in der K\u00fcche. Das kann bei der Zubereitung von Snacks und\/oder Desserts sein. Die K\u00fcchenhilfe k\u00fcmmert sich auch um die Kontrolle und das Auff\u00fcllen der Vorr\u00e4te und hilft beim Auspacken von Lieferungen.    <\/p>\n<\/div><\/div>\n<\/div><\/div>\n\r\n<div class=\"eye-block empty-space empty-space--small pt-md-3 pb-md-3 pt-2 pb-2\" ><\/div>\n<div class=\"ghostkit-grid ghostkit-grid-gap-md equal-height-column\"><div class=\"ghostkit-grid-inner\">\n<div class=\"ghostkit-col ghostkit-col-md-12 ghostkit-col-6 equal-height-columns\"><div class=\"ghostkit-col-content is-layout-flow wp-block-ghostkit-grid-column-is-layout-flow\">\r\n<div class=\"eye-block custom-card bg--lightbeige\">\r\n    <div class=\"custom-card__content\">\r\n        <div class=\"acf-innerblocks-container\">\n\n<h4 class=\"wp-block-heading\" id=\"profiel\">Profil<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Sie sind eine zuverl\u00e4ssige und flexible Person mit einer positiven Arbeitseinstellung, ein echter \"Draufg\u00e4nger\". Au\u00dferdem arbeiten Sie gerne im Team und sind bereit, verschiedene Aufgaben zu \u00fcbernehmen, um die K\u00fcche effizient am Laufen zu halten. <\/p>\n\n<\/div>\r\n    <\/div>\r\n    <\/div><\/div><\/div>\n\n\n\n<div class=\"ghostkit-col ghostkit-col-md-12 ghostkit-col-6\"><div class=\"ghostkit-col-content is-layout-flow wp-block-ghostkit-grid-column-is-layout-flow\">\r\n<div class=\"eye-block custom-card bg--lightbeige\">\r\n    <div class=\"custom-card__content\">\r\n        <div class=\"acf-innerblocks-container\">\n\n<h4 class=\"wp-block-heading\" id=\"profiel\">Wer sind Sie?<\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Sie sind spontan, kollegial und aufger\u00e4umt<\/li>\n\n\n\n<li>Sie k\u00f6nnen gut mit Druck umgehen<\/li>\n\n\n\n<li>Sie haben eine Leidenschaft f\u00fcr die Arbeit im Gastgewerbe<\/li>\n\n\n\n<li>Ihre festen Arbeitstage und -zeiten sind verhandelbar<\/li>\n<\/ul>\n\n<\/div>\r\n    <\/div>\r\n    <\/div><\/div><\/div>\n<\/div><\/div>\n\r\n<div class=\"eye-block empty-space empty-space--small pt-md-3 pb-md-3 pt-2 pb-2\" ><\/div>\n<div class=\"ghostkit-grid ghostkit-grid-gap-md\"><div class=\"ghostkit-grid-inner\">\n<div class=\"ghostkit-col ghostkit-col-md-12 ghostkit-col-6\"><div class=\"ghostkit-col-content is-layout-flow wp-block-ghostkit-grid-column-is-layout-flow\">\r\n<div class=\"eye-block custom-card bg--lightbeige\">\r\n    <div class=\"custom-card__content\">\r\n        <div class=\"acf-innerblocks-container\">\n\n<h4 class=\"wp-block-heading\" id=\"wat-bieden-wij\">Was bieten wir an?<\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Eine au\u00dfergew\u00f6hnliche und sch\u00f6ne Herausforderung in einem dynamischen und wachsenden Unternehmen<\/li>\n\n\n\n<li>Marktgerechtes Gehalt gem\u00e4\u00df dem Tarifvertrag f\u00fcr das Gastgewerbe.<\/li>\n\n\n\n<li>25 Feiertage obv 38-Stunden-Woche<\/li>\n\n\n\n<li>Personalrabatt<\/li>\n\n\n\n<li>R\u00fcckstellung f\u00fcr Pensionen<\/li>\n\n\n\n<li>Regelm\u00e4\u00dfige fantastische Veranstaltungen<\/li>\n\n\n\n<li>Sie arbeiten in der allerbesten Umgebung mit einem kollegialen Team und der nettesten Zielgruppe von Kunden, die es gibt!<\/li>\n<\/ul>\n\n<\/div>\r\n    <\/div>\r\n    <\/div><\/div><\/div>\n\n\n\n<div class=\"ghostkit-col ghostkit-col-md-12 ghostkit-col-6 is-layout-flow wp-block-ghostkit-grid-column-is-layout-flow\"><div class=\"ghostkit-col-content\"><\/div><\/div>\n<\/div><\/div>\n\r\n<div class=\"eye-block empty-space empty-space--large pt-md-5 pb-md-5 pt-4 pb-4\" ><\/div>\r\n<div id=\"anwenden-section\" class=\"eye-block menu-section\" title=\"anwenden\" data-section-name=\"Anwenden\"><\/div>\r\n\n<div class=\"ghostkit-grid ghostkit-grid-gap-md ghostkit-grid-justify-content-center\"><div class=\"ghostkit-grid-inner\">\n<div class=\"ghostkit-col ghostkit-col-lg-12 ghostkit-col-8\"><div class=\"ghostkit-col-content is-layout-flow wp-block-ghostkit-grid-column-is-layout-flow\">\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"afwashulp\">Enthusiastisch?<\/h2>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">Haben wir mit diesem Stellenangebot Ihr Interesse geweckt? Erkennen Sie sich in der Beschreibung wieder und m\u00f6chten Sie sich uns anschlie\u00dfen? Dann senden Sie uns noch heute Ihren Lebenslauf und Ihr Anschreiben an <a href=\"mailto:ramona@koonings.com\"><strong>Stellenausschreibung<\/strong><\/a><a href=\"mailto:vacature@koonings.com\"><strong>@koonings.com<\/strong><\/a>.  <\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">Wer wei\u00df, vielleicht hei\u00dfen wir Sie bald bei Koonings willkommen.<\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><em>Bitte beachten Sie! Bewerbungen ohne Anschreiben werden nicht ber\u00fccksichtigt. <\/em><\/p>\n<\/div><\/div>\n<\/div><\/div>\n","protected":false},"template":"","meta":{"_acf_changed":false,"ghostkit_customizer_options":"","ghostkit_custom_css":"","ghostkit_custom_js_head":"","ghostkit_custom_js_foot":"","ghostkit_typography":""},"sector":[5],"class_list":["post-1636","vacancy","type-vacancy","status-publish","hentry","sector-horeca"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Hilfe in der K\u00fcche - Kasteel Oost<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hilfe in der K\u00fcche - Kasteel Oost\" \/>\n<meta property=\"og:url\" content=\"https:\/\/staging.kasteeloostvalkenburg.com\/de\/overig\/werken-bij\/hilfe-in-der-kueche\/\" \/>\n<meta property=\"og:site_name\" content=\"Kasteel Oost\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Kooningstheweddingpalace\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-10T07:58:11+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"2\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/staging.kasteeloostvalkenburg.com\/de\/overig\/werken-bij\/hilfe-in-der-kueche\/\",\"url\":\"https:\/\/staging.kasteeloostvalkenburg.com\/de\/overig\/werken-bij\/hilfe-in-der-kueche\/\",\"name\":\"Hilfe in der K\u00fcche - Kasteel Oost\",\"isPartOf\":{\"@id\":\"https:\/\/staging.kasteeloostvalkenburg.com\/de\/#website\"},\"datePublished\":\"2025-03-21T13:54:33+00:00\",\"dateModified\":\"2025-11-10T07:58:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/staging.kasteeloostvalkenburg.com\/de\/overig\/werken-bij\/hilfe-in-der-kueche\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/staging.kasteeloostvalkenburg.com\/de\/overig\/werken-bij\/hilfe-in-der-kueche\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/staging.kasteeloostvalkenburg.com\/de\/overig\/werken-bij\/hilfe-in-der-kueche\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/staging.kasteeloostvalkenburg.com\/de\/startseite\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hilfe in der K\u00fcche\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/staging.kasteeloostvalkenburg.com\/de\/#website\",\"url\":\"https:\/\/staging.kasteeloostvalkenburg.com\/de\/\",\"name\":\"Kasteel Oost\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/staging.kasteeloostvalkenburg.com\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/staging.kasteeloostvalkenburg.com\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/staging.kasteeloostvalkenburg.com\/de\/#organization\",\"name\":\"Kasteel Oost\",\"url\":\"https:\/\/staging.kasteeloostvalkenburg.com\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/staging.kasteeloostvalkenburg.com\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/staging.kasteeloostvalkenburg.com\/wp-content\/uploads\/2025\/04\/KasteelOost-logo-darkgray.png\",\"contentUrl\":\"https:\/\/staging.kasteeloostvalkenburg.com\/wp-content\/uploads\/2025\/04\/KasteelOost-logo-darkgray.png\",\"width\":413,\"height\":318,\"caption\":\"Kasteel Oost\"},\"image\":{\"@id\":\"https:\/\/staging.kasteeloostvalkenburg.com\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Kooningstheweddingpalace\",\"https:\/\/www.instagram.com\/kasteeloost\/\",\"https:\/\/www.tiktok.com\/@kooningstheweddingpalace\",\"https:\/\/nl.pinterest.com\/koonings\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hilfe in der K\u00fcche - Kasteel Oost","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"de_DE","og_type":"article","og_title":"Hilfe in der K\u00fcche - Kasteel Oost","og_url":"https:\/\/staging.kasteeloostvalkenburg.com\/de\/overig\/werken-bij\/hilfe-in-der-kueche\/","og_site_name":"Kasteel Oost","article_publisher":"https:\/\/www.facebook.com\/Kooningstheweddingpalace","article_modified_time":"2025-11-10T07:58:11+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"2\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/staging.kasteeloostvalkenburg.com\/de\/overig\/werken-bij\/hilfe-in-der-kueche\/","url":"https:\/\/staging.kasteeloostvalkenburg.com\/de\/overig\/werken-bij\/hilfe-in-der-kueche\/","name":"Hilfe in der K\u00fcche - Kasteel Oost","isPartOf":{"@id":"https:\/\/staging.kasteeloostvalkenburg.com\/de\/#website"},"datePublished":"2025-03-21T13:54:33+00:00","dateModified":"2025-11-10T07:58:11+00:00","breadcrumb":{"@id":"https:\/\/staging.kasteeloostvalkenburg.com\/de\/overig\/werken-bij\/hilfe-in-der-kueche\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/staging.kasteeloostvalkenburg.com\/de\/overig\/werken-bij\/hilfe-in-der-kueche\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/staging.kasteeloostvalkenburg.com\/de\/overig\/werken-bij\/hilfe-in-der-kueche\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/staging.kasteeloostvalkenburg.com\/de\/startseite\/"},{"@type":"ListItem","position":2,"name":"Hilfe in der K\u00fcche"}]},{"@type":"WebSite","@id":"https:\/\/staging.kasteeloostvalkenburg.com\/de\/#website","url":"https:\/\/staging.kasteeloostvalkenburg.com\/de\/","name":"Kasteel Oost","description":"","publisher":{"@id":"https:\/\/staging.kasteeloostvalkenburg.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/staging.kasteeloostvalkenburg.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/staging.kasteeloostvalkenburg.com\/de\/#organization","name":"Kasteel Oost","url":"https:\/\/staging.kasteeloostvalkenburg.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/staging.kasteeloostvalkenburg.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/staging.kasteeloostvalkenburg.com\/wp-content\/uploads\/2025\/04\/KasteelOost-logo-darkgray.png","contentUrl":"https:\/\/staging.kasteeloostvalkenburg.com\/wp-content\/uploads\/2025\/04\/KasteelOost-logo-darkgray.png","width":413,"height":318,"caption":"Kasteel Oost"},"image":{"@id":"https:\/\/staging.kasteeloostvalkenburg.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Kooningstheweddingpalace","https:\/\/www.instagram.com\/kasteeloost\/","https:\/\/www.tiktok.com\/@kooningstheweddingpalace","https:\/\/nl.pinterest.com\/koonings\/"]}]}},"_links":{"self":[{"href":"https:\/\/staging.kasteeloostvalkenburg.com\/de\/wp-json\/wp\/v2\/vacancy\/1636","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.kasteeloostvalkenburg.com\/de\/wp-json\/wp\/v2\/vacancy"}],"about":[{"href":"https:\/\/staging.kasteeloostvalkenburg.com\/de\/wp-json\/wp\/v2\/types\/vacancy"}],"wp:attachment":[{"href":"https:\/\/staging.kasteeloostvalkenburg.com\/de\/wp-json\/wp\/v2\/media?parent=1636"}],"wp:term":[{"taxonomy":"sector","embeddable":true,"href":"https:\/\/staging.kasteeloostvalkenburg.com\/de\/wp-json\/wp\/v2\/sector?post=1636"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}